{"id":2659,"date":"2020-11-24T07:50:34","date_gmt":"2020-11-24T07:50:34","guid":{"rendered":"https:\/\/barek-digital.online\/oio-vivo\/sortiment\/"},"modified":"2025-02-24T11:23:39","modified_gmt":"2025-02-24T10:23:39","slug":"sortiment","status":"publish","type":"page","link":"https:\/\/oio-vivo.com\/de\/sortiment\/","title":{"rendered":"Sortiment"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2659\" class=\"elementor elementor-2659 elementor-1423\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a58902 elementor-section-full_width elementor-section-height-min-height animated-slow elementor-section-height-default elementor-section-items-middle elementor-invisible\" data-id=\"1a58902\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d664728\" data-id=\"d664728\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f217887 elementor-widget elementor-widget-heading\" data-id=\"f217887\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere \u00d6le<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad5f0e9 elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"ad5f0e9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6434d3b\" data-id=\"6434d3b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0792f79 elementor-widget elementor-widget-text-editor\" data-id=\"0792f79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"23\" data-end=\"271\">Verlieben Sie sich in die breite Palette der Aromen unseres ausgezeichneten Oliven\u00f6ls, unter denen Sie sicherlich Ihren Favoriten finden werden, der zu einem unverzichtbaren Gew\u00fcrz f\u00fcr Ihre Gerichte wird und gleichzeitig Ihre Gesundheit st\u00e4rkt.<\/p><p data-start=\"273\" data-end=\"454\">Die Palette der extra nativen Oliven\u00f6le von Oio Vivo umfasst derzeit vier Sorten\u00f6le aus einheimischen Oliven sowie zwei Mischungen von Sorten\u00f6len mit unterschiedlichen Intensit\u00e4ten.<\/p><p data-start=\"456\" data-end=\"684\">Unsere Auswahl besteht aus Vodnjanska Bu\u017ea, Rozinjola, Istrische Bjelica und der seltenen Sorte \u017di\u017eolera, die typisch f\u00fcr das Klima von Vodnjan ist. Unter den Mischungen bieten wir das mildere Bon und das intensivere Gajardo an.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"woocommerce elementor-element elementor-element-b37aefa elementor-arrows-position-outside elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-loop-carousel\" data-id=\"b37aefa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_skin&quot;:&quot;product&quot;,&quot;template_id&quot;:10011,&quot;slides_to_show&quot;:&quot;6&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;.elementor-loop-container&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-carousel.product\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"swiper elementor-loop-container elementor-grid\" role=\"list\" dir=\"ltr\">\n\t\t\t\t<div class=\"swiper-wrapper\" aria-live=\"polite\">\n\t\t<style id=\"loop-10011\">.elementor-widget-theme-post-featured-image .widget-image-caption{color:var( --e-global-color-text );font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-weight:var( --e-global-typography-text-font-weight );}.elementor-10011 .elementor-element.elementor-element-4868b53 img{transition-duration:1s;}.elementor-widget-woocommerce-product-title .elementor-heading-title{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-weight:var( --e-global-typography-primary-font-weight );color:var( --e-global-color-primary );}.elementor-10011 .elementor-element.elementor-element-dd709fe{text-align:center;}.elementor-10011 .elementor-element.elementor-element-dd709fe .elementor-heading-title{font-family:\"Baskervville\", Sans-serif;font-size:20px;font-weight:500;color:#272727;}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"10011\" class=\"elementor elementor-10011 swiper-slide e-loop-item e-loop-item-4593 post-4593 product type-product status-publish has-post-thumbnail product_cat-ol first instock taxable shipping-taxable purchasable product-type-variable\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc73574 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc73574\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-69315fc\" data-id=\"69315fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4868b53 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"4868b53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"431\" height=\"1000\" src=\"https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2021\/02\/roz-kartica-5.png?fit=431%2C1000&amp;ssl=1\" class=\"elementor-animation-grow attachment-large size-large wp-image-10365\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2021\/02\/roz-kartica-5.png?w=431&amp;ssl=1 431w, https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2021\/02\/roz-kartica-5.png?resize=129%2C300&amp;ssl=1 129w\" sizes=\"(max-width: 431px) 100vw, 431px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd709fe elementor-widget elementor-widget-woocommerce-product-title elementor-page-title elementor-widget-heading\" data-id=\"dd709fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-product-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"product_title entry-title elementor-heading-title elementor-size-default\">Rozinjola<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"10011\" class=\"elementor elementor-10011 swiper-slide e-loop-item e-loop-item-4591 post-4591 product type-product status-publish has-post-thumbnail product_cat-ol  instock taxable shipping-taxable purchasable product-type-variable\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc73574 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc73574\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-69315fc\" data-id=\"69315fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4868b53 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"4868b53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"435\" height=\"1000\" src=\"https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2021\/02\/zizolera-1.png?fit=435%2C1000&amp;ssl=1\" class=\"elementor-animation-grow attachment-large size-large wp-image-10368\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2021\/02\/zizolera-1.png?w=435&amp;ssl=1 435w, https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2021\/02\/zizolera-1.png?resize=131%2C300&amp;ssl=1 131w\" sizes=\"(max-width: 435px) 100vw, 435px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd709fe elementor-widget elementor-widget-woocommerce-product-title elementor-page-title elementor-widget-heading\" data-id=\"dd709fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-product-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"product_title entry-title elementor-heading-title elementor-size-default\">Zizolera<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"10011\" class=\"elementor elementor-10011 swiper-slide e-loop-item e-loop-item-4588 post-4588 product type-product status-publish has-post-thumbnail product_cat-ol last instock taxable shipping-taxable purchasable product-type-variable\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc73574 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc73574\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-69315fc\" data-id=\"69315fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4868b53 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"4868b53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"432\" height=\"1000\" src=\"https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2021\/02\/gajardo-kartica-3.png?fit=432%2C1000&amp;ssl=1\" class=\"elementor-animation-grow attachment-large size-large wp-image-10371\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2021\/02\/gajardo-kartica-3.png?w=432&amp;ssl=1 432w, https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2021\/02\/gajardo-kartica-3.png?resize=130%2C300&amp;ssl=1 130w\" sizes=\"(max-width: 432px) 100vw, 432px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd709fe elementor-widget elementor-widget-woocommerce-product-title elementor-page-title elementor-widget-heading\" data-id=\"dd709fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-product-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"product_title entry-title elementor-heading-title elementor-size-default\">Gajardo<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"10011\" class=\"elementor elementor-10011 swiper-slide e-loop-item e-loop-item-4585 post-4585 product type-product status-publish has-post-thumbnail product_cat-ol first instock taxable shipping-taxable purchasable product-type-variable\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc73574 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc73574\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-69315fc\" data-id=\"69315fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4868b53 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"4868b53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"433\" height=\"1000\" src=\"https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2021\/02\/ib-kartica-1.png?fit=433%2C1000&amp;ssl=1\" class=\"elementor-animation-grow attachment-large size-large wp-image-10374\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2021\/02\/ib-kartica-1.png?w=433&amp;ssl=1 433w, https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2021\/02\/ib-kartica-1.png?resize=130%2C300&amp;ssl=1 130w\" sizes=\"(max-width: 433px) 100vw, 433px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd709fe elementor-widget elementor-widget-woocommerce-product-title elementor-page-title elementor-widget-heading\" data-id=\"dd709fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-product-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"product_title entry-title elementor-heading-title elementor-size-default\">Istarska Bjelica<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"10011\" class=\"elementor elementor-10011 swiper-slide e-loop-item e-loop-item-4596 post-4596 product type-product status-publish has-post-thumbnail product_cat-ol  instock taxable shipping-taxable purchasable product-type-variable\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc73574 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc73574\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-69315fc\" data-id=\"69315fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4868b53 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"4868b53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"432\" height=\"1000\" src=\"https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2021\/02\/Bon-3.png?fit=432%2C1000&amp;ssl=1\" class=\"elementor-animation-grow attachment-large size-large wp-image-10380\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2021\/02\/Bon-3.png?w=432&amp;ssl=1 432w, https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2021\/02\/Bon-3.png?resize=130%2C300&amp;ssl=1 130w\" sizes=\"(max-width: 432px) 100vw, 432px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd709fe elementor-widget elementor-widget-woocommerce-product-title elementor-page-title elementor-widget-heading\" data-id=\"dd709fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-product-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"product_title entry-title elementor-heading-title elementor-size-default\">B\u00f2n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"10011\" class=\"elementor elementor-10011 swiper-slide e-loop-item e-loop-item-4599 post-4599 product type-product status-publish has-post-thumbnail product_cat-ol last instock taxable shipping-taxable purchasable product-type-variable\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc73574 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc73574\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-69315fc\" data-id=\"69315fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4868b53 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"4868b53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"432\" height=\"1000\" src=\"https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2021\/02\/vb-kartica-2.png?fit=432%2C1000&amp;ssl=1\" class=\"elementor-animation-grow attachment-large size-large wp-image-10383\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2021\/02\/vb-kartica-2.png?w=432&amp;ssl=1 432w, https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2021\/02\/vb-kartica-2.png?resize=130%2C300&amp;ssl=1 130w\" sizes=\"(max-width: 432px) 100vw, 432px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd709fe elementor-widget elementor-widget-woocommerce-product-title elementor-page-title elementor-widget-heading\" data-id=\"dd709fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-product-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"product_title entry-title elementor-heading-title elementor-size-default\">Vodnjanska Buza<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Voriger\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"N\u00e4chster\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf0372f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"cf0372f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/oio-vivo.com\/trgovina\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Web shop<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4b00ae6 elementor-section-full_width elementor-section-height-min-height elementor-section-items-bottom elementor-section-height-default\" data-id=\"4b00ae6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-778b451\" data-id=\"778b451\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-323e621 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"323e621\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e4e1ed4\" data-id=\"e4e1ed4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f76ee44 elementor-widget elementor-widget-heading\" data-id=\"f76ee44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mensch und Natur<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3778ca4 elementor-widget elementor-widget-text-editor\" data-id=\"3778ca4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"23\" data-end=\"170\">Der Name unseres extra nativen Oliven\u00f6ls Oio Vivo verweist auf die jahrtausendealte Tradition der Oliven\u00f6lproduktion auf der Halbinsel Istrien.<\/p><p data-start=\"172\" data-end=\"297\">Es verbindet die ausgezeichnete geografische Lage f\u00fcr den Olivenanbau mit einem innovativen Ansatz in der Oliven\u00f6lproduktion.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-902c5ea elementor-widget elementor-widget-toggle\" data-id=\"902c5ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1511\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1511\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Read more<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1511\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1511\"><p data-start=\"23\" data-end=\"135\">All dies, kombiniert mit unserer Liebe zu Oliven, hat zur Schaffung eines \u00d6ls von h\u00f6chster Qualit\u00e4t gef\u00fchrt.<\/p><p data-start=\"137\" data-end=\"329\">Der hohe Gehalt an Polyphenolen, die Stabilit\u00e4t des Geschmacks und der Frische sind die Hauptmerkmale unseres Oliven\u00f6ls, das die besten Vorteile f\u00fcr unsere Gesundheit und Langlebigkeit bietet.<\/p><p data-start=\"331\" data-end=\"463\">Unser \u00d6l ist nicht nur Nahrung, sondern fl\u00fcssiges Gold, das in jedem Tropfen eine Geschichte von Exzellenz und Leidenschaft erz\u00e4hlt.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0ff78f5\" data-id=\"0ff78f5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9458720 elementor-section-full_width elementor-section-height-min-height elementor-section-items-bottom elementor-section-height-default\" data-id=\"9458720\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-55d28ad\" data-id=\"55d28ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a4d750c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a4d750c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-95dec8c\" data-id=\"95dec8c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e1df53a\" data-id=\"e1df53a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f3ca67 elementor-widget elementor-widget-heading\" data-id=\"4f3ca67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Idealer Standort<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38b30f2 elementor-widget elementor-widget-text-editor\" data-id=\"38b30f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"23\" data-end=\"148\">Istrien, die Halbinsel im Westen Kroatiens, ist ein mediterranes Klima, das sich hervorragend f\u00fcr den Olivenanbau eignet.<\/p><p data-start=\"150\" data-end=\"262\">Das entdeckten bereits die alten R\u00f6mer, die in Istrien erhebliche Mengen sehr wertvollen Oliven\u00f6ls produzierten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4d67d0 elementor-widget elementor-widget-toggle\" data-id=\"f4d67d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2561\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2561\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Read more<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2561\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2561\"><p data-start=\"23\" data-end=\"319\">Die Region Vodnjan, im S\u00fcden der Halbinsel Istrien, mit sonnenverw\u00f6hnten Olivenhainen, rotem Boden, steinernen Trockenmauern und dem Korridor warmer Meereswinde, der die Ost- und Westk\u00fcste Istriens verbindet, wird als das Klima hervorgehoben, in dem das wertvollste Oliven\u00f6l produziert wurde.<\/p><p data-start=\"321\" data-end=\"526\">Unser Oio Vivo Olivenhain, mit einer Fl\u00e4che von 56 ha und 15.000 B\u00e4umen, befindet sich an einem ausgezeichneten Standort f\u00fcr den Olivenanbau in einer H\u00f6he von 60-120 m \u00fc.d.M., nur 4,5 km vom Meer entfernt.<\/p><p data-start=\"528\" data-end=\"745\">Er liegt zwischen Vodnjan im Norden und Pula im S\u00fcden, im s\u00fcdlichen Teil der Halbinsel Istrien, wo die wohltuenden Str\u00f6mungen warmer Meereswinde vom Ra\u0161ka-Bucht im Osten und dem Brijuni-Archipel im Westen heranf\u00fchren.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-91bce93 elementor-section-full_width elementor-section-height-min-height elementor-section-items-bottom elementor-section-height-default\" data-id=\"91bce93\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9a289c1\" data-id=\"9a289c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3e43846 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3e43846\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-094cab5\" data-id=\"094cab5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-82d1596 elementor-widget elementor-widget-heading\" data-id=\"82d1596\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ernte<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-608467d elementor-widget elementor-widget-text-editor\" data-id=\"608467d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"23\" data-end=\"167\">Der Zeitpunkt der Olivenernte ist eine sehr wichtige Entscheidung, da er die Qualit\u00e4t und den Geschmack des Oliven\u00f6ls erheblich beeinflusst.<\/p><p data-start=\"169\" data-end=\"400\">Das wertvollste \u00d6l, mit einem angenehmen und frischen Geschmack nach Olivenfrucht, nannten die alten R\u00f6mer \u201eEx albis ulivis\u201c, und es wurde bei der fr\u00fchen Ernte gewonnen, wenn sich die Farbe der Frucht von gr\u00fcn zu gr\u00fcn-gelb \u00e4nderte.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-529b5d6 elementor-widget elementor-widget-toggle\" data-id=\"529b5d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8661\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8661\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Read more<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8661\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8661\"><p data-start=\"23\" data-end=\"323\">Die phenolischen Verbindungen, die dem \u00d6l Geschmack und Aroma verleihen, verringern sich mit der Reifung der Oliven. Daher ist es sehr wichtig, den Reifeprozess zu \u00fcberwachen und rechtzeitig die Ernteentscheidung zu treffen, wenn der Polyphenolgehalt in der frischen Olivenfrucht am h\u00f6chsten ist.<\/p><p data-start=\"325\" data-end=\"415\">Wir beginnen die Ernte in den ersten Oktobertagen, wenn es die Wetterbedingungen zulassen.<\/p><p data-start=\"417\" data-end=\"542\">Unsere Oliven ernten wir mit moderner Technologie, mit R\u00fcttelmaschinen, die den Olivenbaum und die Fr\u00fcchte nicht besch\u00e4digen.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d2c761c\" data-id=\"d2c761c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e8e7566 elementor-section-full_width elementor-section-height-min-height elementor-section-items-bottom elementor-section-height-default\" data-id=\"e8e7566\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4f73ca8\" data-id=\"4f73ca8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3efa933 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3efa933\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ea5b833\" data-id=\"ea5b833\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1c1e6f9\" data-id=\"1c1e6f9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70578d0 elementor-widget elementor-widget-heading\" data-id=\"70578d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Verarbeitung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e263031 elementor-widget elementor-widget-text-editor\" data-id=\"e263031\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"23\" data-end=\"89\">Der Prozess der Olivenverarbeitung erfolgt in mehreren Phasen.<\/p><p data-start=\"91\" data-end=\"264\">Die Phasen sind: Reinigung und Waschen der Fr\u00fcchte, Mahlen der Fr\u00fcchte, Mischen der Paste, Trennung des Feststoffs vom Fl\u00fcssigteil und die Separation der \u00d6l-Wasser-Mischung.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f08d66c elementor-widget elementor-widget-toggle\" data-id=\"f08d66c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2521\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2521\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Read more<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2521\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2521\"><p data-start=\"23\" data-end=\"259\">Das endg\u00fcltige Ziel dieses Verfahrens ist die Gewinnung von \u00d6l aus der Olivenfrucht, ohne dass chemische Ver\u00e4nderungen auftreten, die die Qualit\u00e4t des \u00d6ls und seinen biologischen sowie ern\u00e4hrungsphysiologischen Wert beeintr\u00e4chtigen.<\/p><p data-start=\"261\" data-end=\"562\">Dem Prozess des Mischens der Paste muss besondere Aufmerksamkeit geschenkt werden, da hier ein signifikanter Verlust an Polyphenolen auftreten kann, wenn die Temperatur der Mischung 27 Grad Celsius \u00fcberschreitet, was letztlich die Qualit\u00e4t des \u00d6ls und seinen Schutz vor Oxidation beeintr\u00e4chtigen wird.<\/p><p data-start=\"564\" data-end=\"742\">Das so gewonnene \u00d6l wird sofort gefiltert, um R\u00fcckst\u00e4nde der Fruchtmasse und des pflanzlichen Wassers zu entfernen, da dies die Haltbarkeit und Qualit\u00e4t des Oliven\u00f6ls verl\u00e4ngert.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f35197 elementor-section-full_width elementor-section-height-min-height elementor-section-items-bottom elementor-section-height-default\" data-id=\"2f35197\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2cd1620\" data-id=\"2cd1620\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-603a8cc elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"603a8cc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f18b777\" data-id=\"f18b777\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bbd8025 elementor-widget elementor-widget-heading\" data-id=\"bbd8025\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lagerung <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3de854e elementor-widget elementor-widget-text-editor\" data-id=\"3de854e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"23\" data-end=\"408\">Nach dem Verarbeitungsprozess wird das \u00d6l gefiltert und im Olivenhain aufbewahrt, in einem frischen und bel\u00fcfteten Raum bei konstanter Temperatur in Edelstahltanks (Inox), die mit Stickstoffgas verbunden sind, welches den Kontakt des \u00d6ls mit Sauerstoff verhindert. Auf diese Weise wird der Oxidationsprozess verhindert und die wertvollen Eigenschaften des \u00d6ls langfristig erhalten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-618fc1c\" data-id=\"618fc1c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Unsere \u00d6le Verlieben Sie sich in die breite Palette der Aromen unseres ausgezeichneten Oliven\u00f6ls, unter denen Sie sicherlich Ihren Favoriten finden werden, der zu einem unverzichtbaren Gew\u00fcrz f\u00fcr Ihre Gerichte wird und gleichzeitig Ihre Gesundheit st\u00e4rkt. Die Palette der extra nativen Oliven\u00f6le von Oio Vivo umfasst derzeit vier Sorten\u00f6le aus einheimischen Oliven sowie zwei Mischungen [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3280,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-2659","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unsere Oliven\u00f6le - Oio Vivo - Nat\u00fcrliche Quelle f\u00fcr Gesundheit!<\/title>\n<meta name=\"description\" content=\"Das istrische Oliven\u00f6l Oio Vivo - Naturprodukt, der Saft, der aus den Fr\u00fcchten einheimischer Sorten junger, frischer Oliven gepresst wird.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oio-vivo.com\/de\/sortiment\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unsere Oliven\u00f6le - Oio Vivo - Nat\u00fcrliche Quelle f\u00fcr Gesundheit!\" \/>\n<meta property=\"og:description\" content=\"Das istrische Oliven\u00f6l Oio Vivo - Naturprodukt, der Saft, der aus den Fr\u00fcchten einheimischer Sorten junger, frischer Oliven gepresst wird.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oio-vivo.com\/de\/sortiment\/\" \/>\n<meta property=\"og:site_name\" content=\"Oio Vivo\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-24T10:23:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/oio-vivo.com\/wp-content\/uploads\/2020\/12\/Oio-Vivo-featured.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2020\/12\/Oio-Vivo-featured.jpeg?fit=1200%2C628&ssl=1\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"12\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/oio-vivo.com\\\/de\\\/sortiment\\\/\",\"url\":\"https:\\\/\\\/oio-vivo.com\\\/de\\\/sortiment\\\/\",\"name\":\"Unsere Oliven\u00f6le - Oio Vivo - Nat\u00fcrliche Quelle f\u00fcr Gesundheit!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oio-vivo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/oio-vivo.com\\\/de\\\/sortiment\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/oio-vivo.com\\\/de\\\/sortiment\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/oio-vivo.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Oio-Vivo-featured.jpeg?fit=1200%2C628&ssl=1\",\"datePublished\":\"2020-11-24T07:50:34+00:00\",\"dateModified\":\"2025-02-24T10:23:39+00:00\",\"description\":\"Das istrische Oliven\u00f6l Oio Vivo - Naturprodukt, der Saft, der aus den Fr\u00fcchten einheimischer Sorten junger, frischer Oliven gepresst wird.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oio-vivo.com\\\/de\\\/sortiment\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/oio-vivo.com\\\/de\\\/sortiment\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/oio-vivo.com\\\/de\\\/sortiment\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/oio-vivo.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Oio-Vivo-featured.jpeg?fit=1200%2C628&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/oio-vivo.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Oio-Vivo-featured.jpeg?fit=1200%2C628&ssl=1\",\"width\":1200,\"height\":628,\"caption\":\"Oio Vivo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oio-vivo.com\\\/de\\\/sortiment\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Po\u010detna stranica\",\"item\":\"https:\\\/\\\/oio-vivo.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sortiment\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oio-vivo.com\\\/#website\",\"url\":\"https:\\\/\\\/oio-vivo.com\\\/\",\"name\":\"Oio Vivo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/oio-vivo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oio-vivo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oio-vivo.com\\\/#organization\",\"name\":\"Oio Vivo\",\"url\":\"https:\\\/\\\/oio-vivo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/oio-vivo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/oio-vivo.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo.png?fit=185%2C58&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/oio-vivo.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo.png?fit=185%2C58&ssl=1\",\"width\":185,\"height\":58,\"caption\":\"Oio Vivo\"},\"image\":{\"@id\":\"https:\\\/\\\/oio-vivo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unsere Oliven\u00f6le - Oio Vivo - Nat\u00fcrliche Quelle f\u00fcr Gesundheit!","description":"Das istrische Oliven\u00f6l Oio Vivo - Naturprodukt, der Saft, der aus den Fr\u00fcchten einheimischer Sorten junger, frischer Oliven gepresst wird.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oio-vivo.com\/de\/sortiment\/","og_locale":"de_DE","og_type":"article","og_title":"Unsere Oliven\u00f6le - Oio Vivo - Nat\u00fcrliche Quelle f\u00fcr Gesundheit!","og_description":"Das istrische Oliven\u00f6l Oio Vivo - Naturprodukt, der Saft, der aus den Fr\u00fcchten einheimischer Sorten junger, frischer Oliven gepresst wird.","og_url":"https:\/\/oio-vivo.com\/de\/sortiment\/","og_site_name":"Oio Vivo","article_modified_time":"2025-02-24T10:23:39+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/oio-vivo.com\/wp-content\/uploads\/2020\/12\/Oio-Vivo-featured.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2020\/12\/Oio-Vivo-featured.jpeg?fit=1200%2C628&ssl=1","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"12\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/oio-vivo.com\/de\/sortiment\/","url":"https:\/\/oio-vivo.com\/de\/sortiment\/","name":"Unsere Oliven\u00f6le - Oio Vivo - Nat\u00fcrliche Quelle f\u00fcr Gesundheit!","isPartOf":{"@id":"https:\/\/oio-vivo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/oio-vivo.com\/de\/sortiment\/#primaryimage"},"image":{"@id":"https:\/\/oio-vivo.com\/de\/sortiment\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2020\/12\/Oio-Vivo-featured.jpeg?fit=1200%2C628&ssl=1","datePublished":"2020-11-24T07:50:34+00:00","dateModified":"2025-02-24T10:23:39+00:00","description":"Das istrische Oliven\u00f6l Oio Vivo - Naturprodukt, der Saft, der aus den Fr\u00fcchten einheimischer Sorten junger, frischer Oliven gepresst wird.","breadcrumb":{"@id":"https:\/\/oio-vivo.com\/de\/sortiment\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oio-vivo.com\/de\/sortiment\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/oio-vivo.com\/de\/sortiment\/#primaryimage","url":"https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2020\/12\/Oio-Vivo-featured.jpeg?fit=1200%2C628&ssl=1","contentUrl":"https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2020\/12\/Oio-Vivo-featured.jpeg?fit=1200%2C628&ssl=1","width":1200,"height":628,"caption":"Oio Vivo"},{"@type":"BreadcrumbList","@id":"https:\/\/oio-vivo.com\/de\/sortiment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Po\u010detna stranica","item":"https:\/\/oio-vivo.com\/de\/"},{"@type":"ListItem","position":2,"name":"Sortiment"}]},{"@type":"WebSite","@id":"https:\/\/oio-vivo.com\/#website","url":"https:\/\/oio-vivo.com\/","name":"Oio Vivo","description":"","publisher":{"@id":"https:\/\/oio-vivo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oio-vivo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/oio-vivo.com\/#organization","name":"Oio Vivo","url":"https:\/\/oio-vivo.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/oio-vivo.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2020\/10\/logo.png?fit=185%2C58&ssl=1","contentUrl":"https:\/\/i0.wp.com\/oio-vivo.com\/wp-content\/uploads\/2020\/10\/logo.png?fit=185%2C58&ssl=1","width":185,"height":58,"caption":"Oio Vivo"},"image":{"@id":"https:\/\/oio-vivo.com\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/oio-vivo.com\/de\/wp-json\/wp\/v2\/pages\/2659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oio-vivo.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oio-vivo.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oio-vivo.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/oio-vivo.com\/de\/wp-json\/wp\/v2\/comments?post=2659"}],"version-history":[{"count":5,"href":"https:\/\/oio-vivo.com\/de\/wp-json\/wp\/v2\/pages\/2659\/revisions"}],"predecessor-version":[{"id":11732,"href":"https:\/\/oio-vivo.com\/de\/wp-json\/wp\/v2\/pages\/2659\/revisions\/11732"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oio-vivo.com\/de\/wp-json\/wp\/v2\/media\/3280"}],"wp:attachment":[{"href":"https:\/\/oio-vivo.com\/de\/wp-json\/wp\/v2\/media?parent=2659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}